{"id":3617,"date":"2025-05-20T05:56:50","date_gmt":"2025-05-20T05:56:50","guid":{"rendered":"https:\/\/wgpd.intosaicommunity.net\/?page_id=3617"},"modified":"2025-06-02T02:44:35","modified_gmt":"2025-06-02T02:44:35","slug":"idi-wgpd-joint-global-webinar-on-public-debt-sustainability-2","status":"publish","type":"page","link":"https:\/\/wgpd.intosaicommunity.net\/de\/idi-wgpd-joint-global-webinar-on-public-debt-sustainability-2\/","title":{"rendered":"IDI WGPD Joint Global Webinar on Public Debt Sustainability"},"content":{"rendered":"<div style=\"font-family: Arial, sans-serif; color: #333; background-color: #fefefe; padding: 24px; border-radius: 10px; \nbox-shadow: 0 0 10px rgba(0,0,0,0.05); max-width: 960px; margin: auto; line-height: 1.9; font-size: 18px;\"><\/p>\n<h1 style=\"color: #2c3e50; font-size: 34px; text-align: center; margin-bottom: 10px;\">IDI WGPD Joint Global Webinar on Public Debt Sustainability<\/h1>\n<p style=\"text-align: center; font-size: 20px; color: #555;\"><strong>Presentations and Recordings<\/strong><\/p>\n<p style=\"text-align:justify;font-size: 18px; color: #444; margin-bottom: 40px;\">\n    The Working Group on Public Debt, in collaboration with the INTOSAI Development Initiative (IDI), hosted a webinar on Public Debt Sustainability on May 14, 2025. The event featured valuable insights from external stakeholders on the analysis of public debt sustainability, alongside presentations on audit approaches and good practices from selected Supreme Audit Institutions (SAIs). Recordings and relevant materials may be accessed below.\n  <\/p>\n<hr style=\"border: none; border-top: 1px solid #ccc; margin: 30px 0;\">\n<div style=\"margin-bottom: 50px;\">\n<h2 style=\"color: #2980b9; font-size: 26px;\">\ud83d\udcd8 Session 1<\/h2>\n<p><center><br \/>\n   <iframe loading=\"lazy\" width=\"600\" height=\"400\" src=\"https:\/\/www.youtube.com\/embed\/XICrXfiOS1U?si=AJOL8jGqTdjW7nzO\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<div style=\"display: flex; justify-content: center; gap: 10px; margin: 20px 0;\">\n <a href=\"https:\/\/wgpd.intosaicommunity.net\/idi-wgpd-joint-global-webinar-on-public-debt-sustainability-2\/\" style=\"padding: 6px 12px; text-decoration: none; color: white; background-color: #007BFF; border-radius: 4px; border: 1px solid #0056b3;\">English<\/a><br \/>\n  <a href=\"https:\/\/wgpd.intosaicommunity.net\/idi-wgpd-joint-global-webinar-on-public-debt-sustainability-3\/\" style=\"padding: 6px 12px; text-decoration: none; color: #333; background-color: #f0f0f0; border-radius: 4px; border: 1px solid #ccc;\">Arabic<\/a><br \/>\n  <a href=\"https:\/\/wgpd.intosaicommunity.net\/idi-wgpd-joint-global-webinar-on-public-debt-sustainability-5\/\" style=\"padding: 6px 12px; text-decoration: none; color: #333; background-color: #f0f0f0; border-radius: 4px; border: 1px solid #ccc;\">Spanish<\/a><br \/>\n  <a href=\"https:\/\/wgpd.intosaicommunity.net\/idi-wgpd-joint-global-webinar-on-public-debt-sustainability-4\/\" style=\"padding: 6px 12px; text-decoration: none; color: #333; background-color: #f0f0f0; border-radius: 4px; border: 1px solid #ccc;\">French<\/a>\n<\/div>\n<p><\/center><\/p>\n<p style=\"margin-top: 24px;\"><strong>Presentations:<\/strong><\/p>\n<ul style=\"margin-left: 24px;\">\n<li>\n        Public Debt Sustainability: An Introduction <br \/>\n        <span style=\"font-style: italic; color: #555;\">&#8211; Mr. Jaffar Al-Rikabi, Senior Country Economist for the Philippines for the Economic Policy Global Practice, World Bank<\/span><br \/>\n        <a href=\"https:\/\/wgpd.intosaicommunity.net\/wp-content\/uploads\/2025\/05\/World-Bank_IDI-WGPD_public-debt_May-14-2025-v2.pdf\" target=\"_blank\" style=\"color: #0073aa; text-decoration: none;\" rel=\"noopener\">\ud83d\udce5 Download Presentation<\/a>\n      <\/li>\n<li>\n        Debt Sustainability Analysis and Fiscal Reforms <br \/>\n        <span style=\"font-style: italic; color: #555;\">\u2013 Mr. James Webb, Senior Public Sector Economist, Asian Development Bank<\/span><br \/>\n        <a href=\"https:\/\/wgpd.intosaicommunity.net\/wp-content\/uploads\/2025\/05\/ADB-J-Webb-Debt-sustainability-presentation.pptx\" target=\"_blank\" style=\"color: #0073aa; text-decoration: none;\" rel=\"noopener\">\ud83d\udce5 Download Presentation<\/a>\n      <\/li>\n<li>\n        SAI India: Public Debt Sustainability <br \/>\n        <span style=\"font-style: italic; color: #555;\">\u2013 Roli Shukla Malge, Accountant General, SAI India<\/span><br \/>\n        <a href=\"https:\/\/wgpd.intosaicommunity.net\/wp-content\/uploads\/2025\/05\/India_IDI-WGPD_WEBINAR_14.5.2025_Final.pptx\" target=\"_blank\" style=\"color: #0073aa; text-decoration: none;\" rel=\"noopener\">\ud83d\udce5 Download Presentation<\/a>\n      <\/li>\n<li>\n        Sustainability of Public Debt <br \/>\n        <span style=\"font-style: italic; color: #555;\">\u2013 Sherin Hussien Helmy Ghazy, General Manager, ASA&#8217;s Member in the INTOSAI Working Group on Public Debt, SAI Egypt<\/span><br \/>\n        <a href=\"https:\/\/wgpd.intosaicommunity.net\/wp-content\/uploads\/2025\/05\/ASA-OF-EGYPT-The-Presentation.pptx\" target=\"_blank\" style=\"color: #0073aa; text-decoration: none;\" rel=\"noopener\">\ud83d\udce5 Download Presentation<\/a>\n      <\/li>\n<\/ul><\/div>\n<div style=\"margin-bottom: 50px;\">\n<h2 style=\"color: #2980b9; font-size: 26px;\">\ud83d\udcd8 Session 2<\/h2>\n<p><center><br \/>\n <iframe loading=\"lazy\" width=\"600\" height=\"400\" src=\"https:\/\/www.youtube.com\/embed\/sAnD7lgVaCE?si=0LgV7H62eWFL_XIz\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<div style=\"display: flex; justify-content: center; gap: 10px; margin: 20px 0;\">\n <a href=\"https:\/\/wgpd.intosaicommunity.net\/idi-wgpd-joint-global-webinar-on-public-debt-sustainability-2\/\" style=\"padding: 6px 12px; text-decoration: none; color: white; background-color: #007BFF; border-radius: 4px; border: 1px solid #0056b3;\">English<\/a><br \/>\n  <a href=\"https:\/\/wgpd.intosaicommunity.net\/idi-wgpd-joint-global-webinar-on-public-debt-sustainability-3\/\" style=\"padding: 6px 12px; text-decoration: none; color: #333; background-color: #f0f0f0; border-radius: 4px; border: 1px solid #ccc;\">Arabic<\/a><br \/>\n  <a href=\"https:\/\/wgpd.intosaicommunity.net\/idi-wgpd-joint-global-webinar-on-public-debt-sustainability-5\/\" style=\"padding: 6px 12px; text-decoration: none; color: #333; background-color: #f0f0f0; border-radius: 4px; border: 1px solid #ccc;\">Spanish<\/a><br \/>\n  <a href=\"https:\/\/wgpd.intosaicommunity.net\/idi-wgpd-joint-global-webinar-on-public-debt-sustainability-4\/\" style=\"padding: 6px 12px; text-decoration: none; color: #333; background-color: #f0f0f0; border-radius: 4px; border: 1px solid #ccc;\">French<\/a>\n<\/div>\n<p><\/center><\/p>\n<p style=\"margin-top: 24px;\"><strong>Presentations:<\/strong><\/p>\n<ul style=\"margin-left: 24px;\">\n<li>\n        Public Debt Sustainability: An Introduction <br \/>\n        <span style=\"font-style: italic; color: #555;\">\u2013 Mr. Jaffar Al-Rikabi, Senior Country Economist for the Philippines for the Economic Policy Global Practice, World Bank<\/span><br \/>\n        <a href=\"https:\/\/wgpd.intosaicommunity.net\/wp-content\/uploads\/2025\/05\/World-Bank_IDI-WGPD_public-debt_May-14-2025-v2-1.pdf\" target=\"_blank\" style=\"color: #0073aa; text-decoration: none;\" rel=\"noopener\">\ud83d\udce5 Download Presentation<\/a>\n      <\/li>\n<li>\n        Debt vulnerabilities in developing countries amid a challenging global outlook <br \/>\n        <span style=\"font-style: italic; color: #555;\">\u2013 Ms. Daniela Magalh\u00e3es Prates, Senior Economic Affairs Officer, Division of Globalisation and Development Strategies, UNCTAD<\/span><br \/>\n        <a href=\"https:\/\/wgpd.intosaicommunity.net\/wp-content\/uploads\/2025\/05\/UNCTAD-Daniela-Prates-Insotai-2025-UNCTAD-Daniela-Prates-final.pptx\" target=\"_blank\" style=\"color: #0073aa; text-decoration: none;\" rel=\"noopener\">\ud83d\udce5 Download Presentation<\/a>\n      <\/li>\n<li>\n        Brazilian public debt overview: trends, management strategies and audit mandate <br \/>\n        <span style=\"font-style: italic; color: #555;\">\u2013 Joaquim Ramalho de Albuquerque, Auditor, Federal Court of Accounts of Brazil (Tribunal de Contas da Uni\u00e3o, Brazil<\/span><br \/>\n        <a href=\"https:\/\/wgpd.intosaicommunity.net\/wp-content\/uploads\/2025\/05\/BrazilQuestionsBlock1.pptx\" target=\"_blank\" style=\"color: #0073aa; text-decoration: none;\" rel=\"noopener\">\ud83d\udce5 Download Presentation<\/a>\n      <\/li>\n<li>\n        Auditing Public Debt Sustainability: key findings, recommendations, and impacts <br \/>\n        <span style=\"font-style: italic; color: #555;\">\u2013 Joaquim Ramalho de Albuquerque, Auditor, Federal Court of Accounts of Brazil (Tribunal de Contas da Uni\u00e3o, Brazil<\/span><br \/>\n        <a href=\"https:\/\/wgpd.intosaicommunity.net\/wp-content\/uploads\/2025\/05\/BrazilQuestionsBlock2.pptx\" target=\"_blank\" style=\"color: #0073aa; text-decoration: none;\" rel=\"noopener\">\ud83d\udce5 Download Presentation<\/a>\n      <\/li>\n<li>\n        SAI Argentina\u2019s Experience: IDI-WGPD Webinar on Public Debt Sustainability<br \/>\n        <a href=\"https:\/\/wgpd.intosaicommunity.net\/wp-content\/uploads\/2025\/05\/SAI-ARGENTINA-PPT-public-debt-FINAL.pptx\" target=\"_blank\" style=\"color: #0073aa; text-decoration: none;\" rel=\"noopener\">\ud83d\udce5 Download Presentation<\/a>\n      <\/li>\n<li>\n        Concept Note SAI Argentina<br \/>\n        <span style=\"font-style: italic; color: #555;\">\u2013 Sabrina Benedetto, Technical Support, SAI Argentina\u2019s Vice-presidency team for the WGPD<\/span><br \/>\n       <span style=\"font-style: italic; color: #555;\">\u2013 Edda Zanarello, Advisor and technical leader, SAI Argentina\u2019s Vice-presidency team for the WGPD<\/span><br \/>\n       <span style=\"font-style: italic; color: #555;\">\u2013 Camila Paula Carcagno Member, Technical Team, SAI Argentina\u2019s Vice-presidency team for the WGPD<\/span><br \/>\n        <a href=\"https:\/\/wgpd.intosaicommunity.net\/wp-content\/uploads\/2025\/05\/SAI-ArgentinaCONCEPT-NOTE_PRESENTACION-ARGENTINA.pdf\" target=\"_blank\" style=\"color: #0073aa; text-decoration: none;\" rel=\"noopener\">\ud83d\udce5 Download Concept Note <\/a>\n      <\/li>\n<\/ul><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>IDI WGPD Joint Global Webinar on Public Debt Sustainability Presentations and Recordings The Working Group on Public Debt, in collaboration with the INTOSAI Development Initiative (IDI), hosted a webinar on Public Debt Sustainability on May 14, 2025. The event featured valuable insights from external stakeholders on the analysis of public debt sustainability, alongside presentations on &hellip; <a href=\"https:\/\/wgpd.intosaicommunity.net\/de\/idi-wgpd-joint-global-webinar-on-public-debt-sustainability-2\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;IDI WGPD Joint Global Webinar on Public Debt Sustainability&#8221;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"acf":[],"_links":{"self":[{"href":"https:\/\/wgpd.intosaicommunity.net\/de\/wp-json\/wp\/v2\/pages\/3617"}],"collection":[{"href":"https:\/\/wgpd.intosaicommunity.net\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wgpd.intosaicommunity.net\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wgpd.intosaicommunity.net\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wgpd.intosaicommunity.net\/de\/wp-json\/wp\/v2\/comments?post=3617"}],"version-history":[{"count":33,"href":"https:\/\/wgpd.intosaicommunity.net\/de\/wp-json\/wp\/v2\/pages\/3617\/revisions"}],"predecessor-version":[{"id":3713,"href":"https:\/\/wgpd.intosaicommunity.net\/de\/wp-json\/wp\/v2\/pages\/3617\/revisions\/3713"}],"wp:attachment":[{"href":"https:\/\/wgpd.intosaicommunity.net\/de\/wp-json\/wp\/v2\/media?parent=3617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}